{"id":37198,"date":"2022-11-10T09:44:33","date_gmt":"2022-11-10T17:44:33","guid":{"rendered":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/?p=37198"},"modified":"2022-11-10T09:51:55","modified_gmt":"2022-11-10T17:51:55","slug":"cnc-programming-fundamentals-g-code","status":"publish","type":"post","link":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/","title":{"rendered":"G-Code f\u00fcr die CNC-Programmierung"},"content":{"rendered":"\n<p>G-Code? Sie wissen, was man \u00fcber Grundlagen sagt: Lerne sie zuerst, und du wirst dich f\u00fcr immer an sie erinnern. Das Gleiche gilt f\u00fcr die Programmierung von CNC-Maschinen. Selbst wenn sich neue Fertigungstechnologien entwickeln, bleiben die Grundlagen daf\u00fcr, wie Teile mit einem CNC-Programm bearbeitet werden, f\u00fcr immer in Erinnerung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gcode\">G-Code<\/h2>\n\n\n\n<p>In diesem Artikel geht es um die Kernkomponente eines jeden CNC-Programms &#8211; den G-Code.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"g-code\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d39f2b898f.jpg\" width=\"602\" height=\"401\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gcode-auf-einen-blick\"><strong>G-Code auf einen Blick<\/strong><\/h2>\n\n\n\n<p>Hersteller auf der ganzen Welt nutzen die CNC-Programmierung, um die Werkzeuge einer CNC-Maschine zu steuern und Teile zu produzieren. Das Herzst\u00fcck dieses automatisierten Fertigungsprozesses ist eine Reihe von Anweisungen, die einer CNC-Maschine sagen, wo &#8211; und wie &#8211; sie sich bewegen soll. Diese Anweisungen werden G-Code genannt.<\/p>\n\n\n\n<p>G-Code wurde erstmals in den 1960er Jahren von der Electronics Industry Association (EIA) eingef\u00fchrt. Obwohl die offizielle Sprache als RS-274D dokumentiert wurde, wird sie von allen als G-Code bezeichnet. Und warum? Viele der W\u00f6rter oder einzelnen Codeteile, aus denen diese maschinenbasierte Sprache besteht, beginnen mit dem Buchstaben G.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d39f60ab55.png\" width=\"602\" height=\"311\"><\/p>\n\n\n\n<p>Obwohl der G-Code ein universeller Standard sein soll, haben viele CNC-Maschinenhersteller ihren eigenen, einzigartigen Geschmack entwickelt. Am Ende des Tages essen wir alle Eiscreme, aber eine Haas-Maschine hat vielleicht Erdbeergeschmack und eine Tormach-Maschine hat vielleicht Schokoladengeschmack. Aufgrund dieses Unterschieds in den G-Code-Geschmacksrichtungen ist es zwingend erforderlich zu verstehen, wie Ihre eigene CNC-Maschine G-Code verwendet.<\/p>\n\n\n\n<p>Warum der Unterschied bei den G-Code-Geschmacksrichtungen? Es kommt wirklich auf die F\u00e4higkeiten jeder Maschine an. Nehmen Sie eine Maschine, die eine Koordinatensystemdrehung basierend auf Messtaster-Eingaben verarbeiten kann. Sie ben\u00f6tigen eine Reihe von G-Code-Befehlen, die diese Drehung aktivieren oder deaktivieren k\u00f6nnen. Eine andere Maschine ohne diese Einstellm\u00f6glichkeit wird diesen G-Code nicht ben\u00f6tigen.Im Zweifelsfall sollten Sie immer die Dokumentation Ihrer CNC-Maschine zu Rate ziehen, wenn Sie den Rest dieses Artikels durcharbeiten. Wir gehen hier die Grundlagen durch, aber man kann nie wissen, ob Ihre Maschine nicht vielleicht einen etwas anderen Weg zum gleichen Endziel eingeschlagen hat.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gcodebloecke\"><strong>G-Code<\/strong><strong>-Bl\u00f6cke<\/strong><\/h2>\n\n\n\n<p>Der G-Code-Standard wurde zu einer Zeit ver\u00f6ffentlicht, als Maschinen noch \u00fcber wenig Speicher verf\u00fcgten. Aufgrund dieser Speicherbeschr\u00e4nkung ist G-Code eine extrem kompakte und pr\u00e4gnante Sprache, die auf den ersten Blick fast archaisch wirken mag. Nehmen Sie zum Beispiel diese Codezeile:<\/p>\n\n\n\n<p>G01 X1 Y1 F20 T01 M03 S500<\/p>\n\n\n\n<p>In dieser einzigen Zeile geben wir der CNC-Maschine eine Reihe von Anweisungen:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>G01 &#8211; Ausf\u00fchren einer linearen Vorschubbewegung<\/li><li>X1\/Y1 &#8211; Fahre zu diesen X- und Y-Koordinaten<\/li><li>F20 &#8211; Verfahre mit einem Vorschub von 20<\/li><li>T01 &#8211; Werkzeug 1 verwenden, um die Arbeit zu erledigen<\/li><li>M03 &#8211; Spindel einschalten<\/li><li>S500 &#8211; Spindeldrehzahl von 500 einstellen<\/li><\/ul>\n\n\n\n<p>Mehrere Zeilen G-Code wie diese bilden zusammen ein komplettes CNC-Programm. Ihre CNC-Maschine liest den Code dann Zeile f\u00fcr Zeile von links nach rechts und von oben nach unten, wie beim Lesen eines Buches. Jeder Anweisungssatz befindet sich in einer separaten Zeile oder einem Satz.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gcodeprogramme\"><strong>G-Code<\/strong><strong>-Programme<\/strong><\/h2>\n\n\n\n<p>Das Ziel eines jeden G-Code-Programms ist es, Teile auf die sicherste und effizienteste Weise zu produzieren. Um dies zu erreichen, sind die G-Code-S\u00e4tze in der Regel in einer bestimmten Reihenfolge angeordnet, etwa so:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Starten Sie das CNC-Programm.<\/li><li>Laden Sie das gew\u00fcnschte Werkzeug.<\/li><li>Schalten Sie die Spindel ein.<\/li><li>Schalten Sie das K\u00fchlmittel ein.<\/li><li>Fahren Sie auf eine Position \u00fcber einem Teil.<\/li><li>Starten Sie den Bearbeitungsvorgang.<\/li><li>Schalten Sie das K\u00fchlmittel aus.<\/li><li>Schalten Sie die Spindel aus.<\/li><li>Bewegen Sie sich von dem Teil weg an einen sicheren Ort.<\/li><li>Beenden Sie das CNC-Programm.<\/li><\/ol>\n\n\n\n<p>Dieser Ablauf ist ein einfaches Programm, das nur ein Werkzeug f\u00fcr eine Bearbeitung verwendet. In der Praxis werden Sie normalerweise die Schritte 2 bis 9 sp\u00fclen und wiederholen. Das nachstehende G-Code-Programm umfasst beispielsweise alle oben genannten Codebl\u00f6cke mit sich wiederholenden Abschnitten, wo dies erforderlich ist:<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Example of a CNC G-code program with explanations of each code block\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d39f9a90a3.png\" width=\"602\" height=\"655\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"modale-und-adresscodes\"><strong>Modale und Adress-Codes<\/strong><\/h2>\n\n\n\n<p>Wie andere Programmiersprachen auch, kann G-Code eine Aktion unbegrenzt wiederholen, bis sie gestoppt wird. Dieser Schleifenprozess verwendet modalen Code, der solange wirkt, bis Sie ihn entweder abschalten oder durch einen anderen modalen Code modifizieren. Zum Beispiel ist M03 ein modaler Code, der eine Spindel unendlich lange laufen l\u00e4sst, bis Sie ihm mit M05 sagen, dass er aufh\u00f6ren soll. Warten Sie einen Moment. Dieses Wort (denken Sie daran: ein Wort ist ein kleines St\u00fcck Code) hat nicht mit einem G begonnen, aber es ist trotzdem G-Code. W\u00f6rter, die mit einem M beginnen, sind Maschinencodes, und sie schalten Maschinenfunktionen wie K\u00fchlmittel, Spindel und Spanner ein oder aus. Ich werde im n\u00e4chsten Abschnitt einige g\u00e4ngige auflisten, aber Sie k\u00f6nnen eine Liste der M-Codes Ihrer Maschine in der Dokumentation finden.<\/p>\n\n\n\n<p>Der G-Code enth\u00e4lt auch eine vollst\u00e4ndige Liste der Adresscodes. Sie k\u00f6nnen sich diese als das W\u00f6rterbuch f\u00fcr G-Code vorstellen, das bestimmte Verhaltensweisen definiert. Adresscodes beginnen mit der Buchstabenbezeichnung, wie G, und dann mit einer Reihe von Zahlen. Zum Beispiel definiert X2 einen Adresscode f\u00fcr die X-Koordinate, wobei 2 der Wert auf der X-Achse ist, zu dem die Maschine bewegt werden soll.<\/p>\n\n\n\n<p>Die vollst\u00e4ndige Liste der Adresscodes umfasst:<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"415\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d39fe6bd5c.png\" alt=\"Examples of address code parameters\"><\/p>\n\n\n\n<p>Einem G-Code-Programm k\u00f6nnen mehrere Sonderzeichen-Codes hinzugef\u00fcgt werden. Diese werden typischerweise zum Starten eines Programms, zum Auskommentieren von Text oder zum Ignorieren von Zeichen verwendet und umfassen:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>% Beginnt oder beendet ein CNC-Programm<\/li><li>() Definiert einen Kommentar, der von einem CNC-Bediener geschrieben wird; gelegentlich m\u00fcssen diese in Gro\u00dfbuchstaben sein<\/li><li>\/ Ignoriert alle Zeichen, die nach dem Schr\u00e4gstrich kommen<\/li><li>; Legt fest, wann ein Code-Block endet; wird in einem Texteditor nicht angezeigt<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gcodes-amp-mcodes-erklaert\">G-Codes &amp; M-Codes erkl\u00e4rt<\/h2>\n\n\n\n<p>G- und M-Codes machen den gr\u00f6\u00dften Teil Ihres CNC-Programms aus. Codes, die mit G beginnen, bereiten Ihre Maschine auf die Ausf\u00fchrung einer bestimmten Art von Bewegung vor. Die gebr\u00e4uchlichsten G-Codes, denen Sie in jedem CNC-Programm immer wieder begegnen werden, sind<\/p>\n\n\n\n<p>G0 &#8211; Eilgang<\/p>\n\n\n\n<p>Dieser Code weist eine CNC-Maschine an, so schnell wie m\u00f6glich zu einer bestimmten Koordinatenposition zu fahren. G0 verf\u00e4hrt die Maschine Achse f\u00fcr Achse, d. h., sie verf\u00e4hrt zuerst entlang beider Achsen und beendet die Bewegung auf der Achse, die sich nicht in Position befindet. Ein Beispiel f\u00fcr diese Bewegung sehen Sie in der Abbildung unten:<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"265\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d3a0239ff7.png\" alt=\"Diagram showing the motion of a G00 rapid move\"><\/p>\n\n\n\n<p>Dieser Code weist die Maschine an, in einer geraden Linie zu einer Koordinatenposition mit einem definierten Vorschub zu verfahren. Zum Beispiel: G1 X1 Y1 F32 f\u00e4hrt die Maschine zu den Koordinaten X1, Y1, mit einem Vorschub von 32.<\/p>\n\n\n\n<p>G2, G3 &#8211; Bogen im Uhrzeigersinn, Bogen gegen den UhrzeigersinnDiese Codes weisen die CNC-Maschine an, in einem Bogen zu einer Zielkoordinate zu fahren. Zwei zus\u00e4tzliche Koordinaten, I und J, definieren die zentrale Position des Bogens, wie unten gezeigt:<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"252\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d3a05529d1.png\" alt=\"Diagram showing CW and CCW arc interpolation using G02 and G03\"><\/p>\n\n\n\n<p>G17, G18, G19 &#8211; Ebenenkennungen<\/p>\n\n\n\n<p>Diese Codes legen fest, auf welcher Ebene ein Kreisbogen bearbeitet werden soll. Standardm\u00e4\u00dfig verwendet Ihre CNC-Maschine G17, das ist die XY-Ebene. Die anderen beiden Ebenen sind in der Abbildung unten dargestellt:<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"377\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d3a096b7b4.png\" alt=\"Plane selection diagram showing XY, YZ, and ZX planes\"><\/p>\n\n\n\n<p>G40, G41, G42 &#8211; Fr\u00e4serdurchmesserkompensation<\/p>\n\n\n\n<p>Diese Codes definieren die Fr\u00e4serdurchmesser-Kompensation oder CDC, die es einer CNC-Maschine erm\u00f6glicht, ihr Werkzeug links oder rechts von einer definierten Bahn zu positionieren. Ein D-Register speichert den Offset f\u00fcr jedes Werkzeug.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"454\" height=\"254\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d3a0c8c7f9.png\" alt=\"Diameter offset table with example values in tool 1.\"><\/p>\n\n\n\n<p>G43 &#8211; Werkzeugl\u00e4ngenkorrekturDieser Code definiert die L\u00e4nge der einzelnen Werkzeuge unter Verwendung einer Z-Achsenh\u00f6he. Dies erm\u00f6glicht der CNC-Maschine zu verstehen, wo sich die Spitze eines Werkzeugs in Bezug auf das zu bearbeitende Werkst\u00fcck befindet. Ein Register definiert die Werkzeugl\u00e4ngenkorrekturen, wobei H der Werkzeugl\u00e4ngenversatz und Z die L\u00e4nge des Werkzeugs ist.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"454\" height=\"248\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d3a0f92a26.png\" alt=\"Tool Length offset table with tool length value examples\"><\/p>\n\n\n\n<p>G54 &#8211; Arbeitsversatz<\/p>\n\n\n\n<p>Dieser Code wird verwendet, um einen Aufspann-Offset zu definieren, der den Abstand von den internen Koordinaten einer Maschine zum Nullpunkt auf einem Werkst\u00fcck bestimmt. In der folgenden Tabelle ist nur G54 mit einer Offset-Definition versehen. Sie k\u00f6nnen jedoch mehrere Offsets programmieren, wenn ein Job die gleichzeitige Bearbeitung mehrerer Teile erfordert.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"187\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d3a12ab1fa.png\" alt=\"Work Offset table with values for a work offset included in the G54\"><\/p>\n\n\n\n<p>M-CodesM-Codes sind Maschinencodes, die sich zwischen verschiedenen CNC-Maschinen unterscheiden k\u00f6nnen. Diese Codes steuern Funktionen auf Ihrer CNC-Maschine, wie z. B. K\u00fchlmittel- und Spindelrichtungen. Einige der gebr\u00e4uchlichsten M-Codes sind:<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"211\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d3a162d38c.png\" alt=\"Sample of common machine codes or m-codes\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"festgelegte-zyklen-im-gcode\"><strong>Festgelegte Zyklen im <\/strong><strong>G-Code<\/strong><\/h2>\n\n\n\n<p>Der letzte Aspekt des G-Codes, den wir ansprechen wollen, sind Festzyklen. Diese sind vergleichbar mit Methoden oder Funktionen in der Computerprogrammierung. Sie erm\u00f6glichen es Ihnen, eine komplizierte Aktion in nur wenigen Codezeilen auszuf\u00fchren, ohne alle Details abtippen zu m\u00fcssen.<\/p>\n\n\n\n<p>Nehmen Sie z. B. den untenstehenden Festzyklus. Hier weisen wir das CNC-Werkzeug in nur zwei Codezeilen auf der linken Seite an, ein Loch mit einem Tieflochbohrer zu erzeugen. Dieselbe Aktion erfordert \u00fcber 20 Zeilen regul\u00e4ren G-Code.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"480\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d3a1a20235.png\" alt=\"Canned Cycle vs Expanded G Code\"><\/p>\n\n\n\n<p>Einige g\u00e4ngige Bohrzyklen sind:<\/p>\n\n\n\n<p>G81 &#8211; Einfacher Bohrer-Zyklus<\/p>\n\n\n\n<p>Dieser Zyklus erstellt ein Loch, indem er bis zu einer bestimmten Z-Achsen-Koordinate eintaucht und sich dann zur\u00fcckzieht. Die Programmierung dieses Zyklus erfordert eine Tiefe, Vorschubgeschwindigkeit, XY-Koordinaten und die Ebene, auf der gebohrt werden soll.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"517\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d3a1e14075.png\"><\/p>\n\n\n\n<p>G83 &#8211; Tieflochbohren<\/p>\n\n\n\n<p>Dieser Zyklus wird zum schnellen Bohren tiefer L\u00f6cher verwendet. Ein Werkzeug bohrt zuerst eine definierte Strecke und zieht sich dann zur\u00fcck, wodurch das Material aus der Bohrung entfernt wird und das K\u00fchlmittel die Sp\u00e4ne wegsp\u00fclen kann. Die einfachste Implementierung dieses Zyklus erfordert eine Anfangsh\u00f6he, eine Vorschubebene, ein Bohrungsinkrement und eine Tiefe.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"521\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d3a2119d4d.png\" alt=\"Diagram showing peck drilling motion and parameters\"><\/p>\n\n\n\n<p>G98 &#8211; R\u00fcckzug auf die anf\u00e4ngliche rasche H\u00f6he<\/p>\n\n\n\n<p>Dieser Zyklus f\u00e4hrt ein Werkzeug auf eine Freifl\u00e4che zwischen den Bohrungen zur\u00fcck, was hilft, Spannungen zu vermeiden. Die Programmierung dieses Zyklus erfordert eine Anfangsh\u00f6he und eine Vorschubebene, auf der gebohrt werden soll.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"527\" src=\"https:\/\/autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636d3a2504df9.png\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"zuerst-die-grundlagen\"><strong>Zuerst die Grundlagen<\/strong><\/h2>\n\n\n\n<p>Auch wenn Sie niemals Ihr eigenes CNC-Programm von Hand schreiben werden, wird Ihnen das Verst\u00e4ndnis der Grundlagen von G-Code einen Vorsprung in Ihrer CNC-Programmierkarriere verschaffen. Das Kernverhalten bleibt hersteller\u00fcbergreifend intakt, auch wenn sich der eigentliche G-Code leicht unterscheidet. Letztendlich kombinieren Sie Koordinaten, Vorschubgeschwindigkeiten und eine Reihe von definierbaren Aktionen, um ein Werkzeug zu bewegen und ein Teil erfolgreich zu bearbeiten.<\/p>\n\n\n\n<p>Einige Ratgeber empfehlen, die g\u00e4ngigsten G- und M-Codes auswendig zu lernen. Das mag zwar funktionieren, aber \u00dcbung macht den Meister! Wenden Sie Ihre G-Code-Grundlagen w\u00e4hrend Ihrer gesamten Laufbahn kontinuierlich an und frischen Sie sie auf, damit sie Ihnen erhalten bleiben. <a href=\"http:\/\/www.helmancnc.com\/g-codes-cnc-programming-quiz\/\">Hier ist ein kurzes Quiz, um zu sehen, wo Sie stehen<\/a>.Sind Sie bereit, Ihr Wissen \u00fcber CNC-Programmierung und G-Code in die Praxis umzusetzen? Testen Sie Fusion 360 noch heute!<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><?xml encoding=\"utf-8\" ?><div class=\"wp-block-button\"><a href=\"https:\/\/www.autodesk.de\/products\/fusion-360\/overview?mktvar002=4333583001%7CORG%7C&amp;utm_medium=social&amp;utm_source=other&amp;utm_campaign=4333583dmblogf360&amp;utm_id=4333583001\" class=\"\n            MuiButtonBase-root MuiButton-root\n            wp-block-button__link\n            \n            \n            \n            MuiButton-contained\n        \">\n\n        <span class=\"MuiButton-label\">\n            \n            \nGRATIS TESTVERSION DOWNLOADEN\n\n            \n        <\/span>\n    <\/a>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>In diesem Artikel geht es um die Kernkomponente eines jeden CNC-Programms &#8211; den G-Code.<\/p>\n","protected":false},"author":1894,"featured_media":36612,"menu_order":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[340,257],"tags":[],"coauthors":[],"class_list":["post-37198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mechanical-engineering-de","category-uncategorized-de","dhig-theme--light"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>G-Code f\u00fcr die CNC-Programmierung - Fusion Blog<\/title>\n<meta name=\"description\" content=\"In diesem Artikel geht es um die Kernkomponente eines jeden CNC-Programms - den G-Code.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G-Code f\u00fcr die CNC-Programmierung - Fusion Blog\" \/>\n<meta property=\"og:description\" content=\"In diesem Artikel geht es um die Kernkomponente eines jeden CNC-Programms - den G-Code.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/\" \/>\n<meta property=\"og:site_name\" content=\"Fusion Blog\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-10T17:44:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T17:51:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636a675769663.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marti Deans\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@marti_deans\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marti Deans\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Marti Deans\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"G-Code f\u00fcr die CNC-Programmierung - Fusion Blog","description":"In diesem Artikel geht es um die Kernkomponente eines jeden CNC-Programms - den G-Code.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/","og_locale":"de_DE","og_type":"article","og_title":"G-Code f\u00fcr die CNC-Programmierung - Fusion Blog","og_description":"In diesem Artikel geht es um die Kernkomponente eines jeden CNC-Programms - den G-Code.","og_url":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/","og_site_name":"Fusion Blog","article_published_time":"2022-11-10T17:44:33+00:00","article_modified_time":"2022-11-10T17:51:55+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636a675769663.jpg","type":"image\/jpeg"}],"author":"Marti Deans","twitter_card":"summary_large_image","twitter_creator":"@marti_deans","twitter_misc":{"Verfasst von":"Marti Deans","Gesch\u00e4tzte Lesezeit":"10 Minuten","Written by":"Marti Deans"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/#article","isPartOf":{"@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/"},"author":{"name":"Marti Deans","@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/#\/schema\/person\/667bff6d55b30422effdbdb4f3c0877f"},"headline":"G-Code f\u00fcr die CNC-Programmierung","datePublished":"2022-11-10T17:44:33+00:00","dateModified":"2022-11-10T17:51:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/"},"wordCount":1685,"image":{"@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/#primaryimage"},"thumbnailUrl":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636a675769663.jpg","articleSection":["Maschinenbau","Unkategorisiert"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/","url":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/","name":"G-Code f\u00fcr die CNC-Programmierung - Fusion Blog","isPartOf":{"@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/#primaryimage"},"image":{"@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/#primaryimage"},"thumbnailUrl":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636a675769663.jpg","datePublished":"2022-11-10T17:44:33+00:00","dateModified":"2022-11-10T17:51:55+00:00","author":{"@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/#\/schema\/person\/667bff6d55b30422effdbdb4f3c0877f"},"description":"In diesem Artikel geht es um die Kernkomponente eines jeden CNC-Programms - den G-Code.","breadcrumb":{"@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/#primaryimage","url":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636a675769663.jpg","contentUrl":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2022\/11\/img_636a675769663.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/cnc-programming-fundamentals-g-code\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"G-Code f\u00fcr die CNC-Programmierung"}]},{"@type":"WebSite","@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/#website","url":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/","name":"Fusion Blog","description":"Product updates, tips, tutorials and community news.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/#\/schema\/person\/667bff6d55b30422effdbdb4f3c0877f","name":"Marti Deans","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2018\/05\/Marti-1-150x150.jpg99ef33b5828b3465091d7bf7166badc1","url":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2018\/05\/Marti-1-150x150.jpg","contentUrl":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/wp-content\/uploads\/2018\/05\/Marti-1-150x150.jpg","caption":"Marti Deans"},"description":"Marti graduated from University of California, Berkeley where she earned her B.S. Mechanical Engineering and explored manual and CNC manufacturing processes in the Berkeley Student Machine Shop using MasterCAM, HSMWorks, and InventorHSM. Using this experience, she has been working at Autodesk for over 2 years, first developing training and adoption strategies for Fusion 360 users with a focus in manufacturing and now driving awareness for Fusion 360 and its manufacturing capabilities.","sameAs":["https:\/\/x.com\/marti_deans"],"url":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/author\/mdeans\/"}]}},"_links":{"self":[{"href":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/wp-json\/wp\/v2\/posts\/37198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/wp-json\/wp\/v2\/users\/1894"}],"replies":[{"embeddable":true,"href":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/wp-json\/wp\/v2\/comments?post=37198"}],"version-history":[{"count":0,"href":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/wp-json\/wp\/v2\/posts\/37198\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/wp-json\/wp\/v2\/media\/36612"}],"wp:attachment":[{"href":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/wp-json\/wp\/v2\/media?parent=37198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/wp-json\/wp\/v2\/categories?post=37198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/wp-json\/wp\/v2\/tags?post=37198"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.autodesk.com\/products\/fusion-360\/blog\/de\/wp-json\/wp\/v2\/coauthors?post=37198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}